{"id":21313,"date":"2023-09-26T17:14:47","date_gmt":"2023-09-26T15:14:47","guid":{"rendered":"https:\/\/mucciaccia.com\/?page_id=21313"},"modified":"2026-06-12T09:08:44","modified_gmt":"2026-06-12T07:08:44","slug":"mucciaccia-gallery-roma","status":"publish","type":"page","link":"https:\/\/mucciaccia.com\/it\/mucciaccia-gallery-roma\/","title":{"rendered":"Mucciaccia Gallery Roma"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px|0px|0px|0px|false|false&#8221; custom_padding=&#8221;0px|0px|0px|0px|false|false&#8221; hover_enabled=&#8221;0&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][et_pb_row _builder_version=&#8221;4.23&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.23&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/mucciaccia.com\/wp-content\/uploads\/2026\/06\/Summer-Collection-2026-Mucciaccia-Gallery-Rome-Detail.jpg.webp&#8221; alt=&#8221;by Piero Pizzi Cannella&#8221; title_text=&#8221;Summer Collection 2026, Mucciaccia Gallery, Rome &#8211; Detail.jpg&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; height=&#8221;500px&#8221; height_tablet=&#8221;400px&#8221; height_phone=&#8221;280px&#8221; height_last_edited=&#8221;on|phone&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; hover_enabled=&#8221;0&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][et_pb_row _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text ul_position=&#8221;inside&#8221; _builder_version=&#8221;4.27.6&#8243; text_font=&#8221;||||||||&#8221; text_font_size=&#8221;1.2rem&#8221; text_line_height=&#8221;1.5rem&#8221; ul_font=&#8221;||||||||&#8221; header_font=&#8221;|600|||||||&#8221; header_font_size=&#8221;1.8rem&#8221; header_line_height=&#8221;1.8rem&#8221; header_2_font_size=&#8221;1.5rem&#8221; header_2_line_height=&#8221;1.5rem&#8221; header_3_font=&#8221;|600|||||||&#8221; header_3_font_size=&#8221;16px&#8221; header_3_line_height=&#8221;1.3em&#8221; header_6_font=&#8221;|300|||||||&#8221; header_6_font_size=&#8221;22px&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;0px||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; hover_enabled=&#8221;0&#8243; text_font_size_tablet=&#8221;1.1rem&#8221; text_font_size_phone=&#8221;1rem&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; text_line_height_tablet=&#8221;1.5rem&#8221; text_line_height_phone=&#8221;1.5rem&#8221; text_line_height_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;1.4rem&#8221; header_font_size_phone=&#8221;1.1rem&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; header_line_height_tablet=&#8221;1.4rem&#8221; header_line_height_phone=&#8221;1.1rem&#8221; header_line_height_last_edited=&#8221;on|tablet&#8221; header_2_font_size_tablet=&#8221;1.5rem&#8221; header_2_font_size_phone=&#8221;1.5rem&#8221; header_2_font_size_last_edited=&#8221;on|desktop&#8221; header_2_line_height_tablet=&#8221;1.5rem&#8221; header_2_line_height_phone=&#8221;1.5rem&#8221; header_2_line_height_last_edited=&#8221;on|tablet&#8221; header_3_font_size_tablet=&#8221;&#8221; header_3_font_size_phone=&#8221;18px&#8221; header_3_font_size_last_edited=&#8221;on|desktop&#8221; text_text_align=&#8221;center&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h1 style=\"text-align: left;\">MUCCIACCIA GALLERY | ROMA<\/h1>\n<h2 style=\"text-align: left;\">Summer Collection 2026<\/h2>\n<p style=\"text-align: left;\">10 giugno &#8211; 31 agosto 2026<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wb3N0Iiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjMwODE4In19@&#8221; button_text=&#8221;Per saperne di pi\u00f9&#8230;&#8221; _builder_version=&#8221;4.27.6&#8243; _dynamic_attributes=&#8221;button_url&#8221; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;15px&#8221; custom_margin=&#8221;20px||||false|false&#8221; custom_padding=&#8221;0px||||false|false&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Header&#8221; module_id=&#8221;chiamataallearti&#8221; _builder_version=&#8221;4.24.3&#8243; background_enable_image=&#8221;off&#8221; background_size=&#8221;initial&#8221; background_repeat=&#8221;repeat&#8221; custom_margin=&#8221;0px||||false|false&#8221; custom_padding=&#8221;60px||||false|false&#8221; disabled=&#8221;on&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.22.2&#8243; use_custom_width=&#8221;on&#8221; width_unit=&#8221;off&#8221; custom_width_percent=&#8221;100%&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.24.0&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;|500|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_font_size=&#8221;23px&#8221; header_3_font=&#8221;|700||on|||||&#8221; header_3_text_color=&#8221;rgba(0,0,0,0.35)&#8221; header_3_font_size=&#8221;12px&#8221; header_3_letter_spacing=&#8221;5px&#8221; header_3_line_height=&#8221;2em&#8221; transform_translate_linked=&#8221;off&#8221; text_orientation=&#8221;center&#8221; module_alignment=&#8221;center&#8221; hover_transition_duration=&#8221;0ms&#8221; header_2_font_size_tablet=&#8221;23px&#8221; header_2_font_size_phone=&#8221;16px&#8221; header_2_font_size_last_edited=&#8221;on|tablet&#8221; text_text_align=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Open Call<\/h2>\n<p>[\/et_pb_text][et_pb_divider _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.19.2&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/mucciaccia.com\/wp-content\/uploads\/2024\/02\/Chiamata-arti-2024-Open-call.webp&#8221; alt=&#8221;Open Call | Chiamata alle Arti 2024 &#8221; title_text=&#8221;Chiamata arti 2024 Open call&#8221; show_in_lightbox=&#8221;on&#8221; _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; filter_saturate=&#8221;97%&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: justify;\">Summer Exhibition | Chiamata alle Arti | 2024<\/p>\n<p style=\"text-align: justify;\">Open Call &#8211; Invito di partecipazione a tutte le Accademie di Belle Arti in Italia<\/p>\n<p style=\"text-align: justify;\">Mucciaccia Gallery Project\u00a0 \u00e8 lieta di annunciare la quarta edizione di Chiamata alle Arti che si terr\u00e0 durante i mesi estivi di luglio e agosto 2024.<\/p>\n<p style=\"text-align: justify;\">Chiamata alle Arti \u00e8 una mostra collettiva, organizzata in\u00a0collaborazione con le Accademie di Belle Arti in Italia, un progetto nato nel 2021 per sostenere le Accademie di\u00a0 Belli Arti italiane con l\u2019intento\u00a0di dare visibilit\u00e0 agli studenti e alla loro creativit\u00e0 artistica.<\/p>\n<p style=\"text-align: justify;\">Invitiamo tutte le Accademie di Belle Arti in Italia a presentare un massimo di dieci portfoli di studenti dell\u2019ultimo anno di Triennale, o che stanno frequentando il corso magistrale.<\/p>\n<p style=\"text-align: justify;\">Ricordiamo che gli studenti che hanno esposto alle precedenti edizioni non possono partecipare nuovamente.<\/p>\n<p style=\"text-align: justify;\">La scadenza per le candidature \u00e8 il 31 marzo 2024. La galleria prender\u00e0 in considerazione solo i portfoli di studenti presentati dai professori delle Accademie, gli studenti non possono inoltrare direttamente le loro candidature.<\/p>\n<p style=\"text-align: left;\">Per ulteriori informazioni si prega di contattare la galleria:<a href=\"mailto:project@mucciaccia.com\"> project@mucciaccia.com<\/a><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Header&#8221; module_id=&#8221;past_exhibitions&#8221; _builder_version=&#8221;4.27.4&#8243; custom_margin=&#8221;0px||0px||false|false&#8221; custom_padding=&#8221;20px||0px||false|false&#8221; disabled=&#8221;on&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; use_custom_width=&#8221;on&#8221; width_unit=&#8221;off&#8221; custom_width_percent=&#8221;100%&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text module_class=&#8221;hyperlink-color-image&#8221; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;|500|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_font_size=&#8221;23px&#8221; header_3_font=&#8221;|700||on|||||&#8221; header_3_text_color=&#8221;rgba(0,0,0,0.35)&#8221; header_3_font_size=&#8221;12px&#8221; header_3_letter_spacing=&#8221;5px&#8221; header_3_line_height=&#8221;2em&#8221; transform_translate_linked=&#8221;off&#8221; text_orientation=&#8221;center&#8221; module_alignment=&#8221;center&#8221; hover_transition_duration=&#8221;0ms&#8221; header_2_font_size_tablet=&#8221;23px&#8221; header_2_font_size_phone=&#8221;16px&#8221; header_2_font_size_last_edited=&#8221;on|tablet&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2 style=\"text-align: left;\">Prossime mostre<\/h2>\n<p>[\/et_pb_text][et_pb_divider color=&#8221;#c9c9c9&#8243; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.24.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/mucciaccia.com\/wp-content\/uploads\/2025\/07\/Austin-Young-The-Garden-2025-digital-collage-on-watercolor-paper-70-x-100-cm-PNG.webp&#8221; alt=&#8221;Austin Young, The Garden, 2025, digital collage on watercolor paper, 70 x 100 cm&#8221; title_text=&#8221;Austin Young, The Garden, 2025, digital collage on watercolor paper, 70 x 100 cm&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; height=&#8221;260px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong>Beauty! A solo exhibition by Austin Young<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;12px&#8221; text_line_height=&#8221;1rem&#8221; custom_padding=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Opening: venerd\u00ec 26 settembre 2025 &#8211; ore 18.00<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/mucciaccia.com\/wp-content\/uploads\/2024\/05\/chiamata-alle-arti-2024.webp&#8221; alt=&#8221;Visions | Emma Talbot&#8221; title_text=&#8221;chiamata alle arti 2024 &#8211; Mucciaccia Gallery&#8221; _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; height=&#8221;260px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong>Chiamata alle Arti 2024<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.25.1&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;12px&#8221; text_line_height=&#8221;1rem&#8221; custom_padding=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Opening 9 luglio, ore 18:00<br \/>10 luglio &#8211; 30 agosto 2024<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.23&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Header&#8221; module_id=&#8221;past_exhibitions&#8221; _builder_version=&#8221;4.24.0&#8243; custom_margin=&#8221;0px||0px||false|false&#8221; custom_padding=&#8221;20px||0px||false|false&#8221; disabled=&#8221;on&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; use_custom_width=&#8221;on&#8221; width_unit=&#8221;off&#8221; custom_width_percent=&#8221;100%&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text module_class=&#8221;hyperlink-color-image&#8221; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;|500|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_font_size=&#8221;23px&#8221; header_3_font=&#8221;|700||on|||||&#8221; header_3_text_color=&#8221;rgba(0,0,0,0.35)&#8221; header_3_font_size=&#8221;12px&#8221; header_3_letter_spacing=&#8221;5px&#8221; header_3_line_height=&#8221;2em&#8221; transform_translate_linked=&#8221;off&#8221; text_orientation=&#8221;center&#8221; module_alignment=&#8221;center&#8221; hover_transition_duration=&#8221;0ms&#8221; header_2_font_size_tablet=&#8221;23px&#8221; header_2_font_size_phone=&#8221;16px&#8221; header_2_font_size_last_edited=&#8221;on|tablet&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2 style=\"text-align: left;\">Prossime mostre<\/h2>\n<p>[\/et_pb_text][et_pb_divider color=&#8221;#c9c9c9&#8243; _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_blog fullwidth=&#8221;off&#8221; posts_number=&#8221;40&#8243; include_categories=&#8221;280&#8243; use_manual_excerpt=&#8221;off&#8221; excerpt_length=&#8221;0&#8243; show_author=&#8221;off&#8221; show_date=&#8221;off&#8221; show_categories=&#8221;off&#8221; show_excerpt=&#8221;off&#8221; disabled_on=&#8221;on|on|on&#8221; module_class=&#8221;et_blog_grid_equal_height&#8221; _builder_version=&#8221;4.23&#8243; _module_preset=&#8221;default&#8221; header_level=&#8221;h3&#8243; header_font=&#8221;|600|||||||&#8221; header_text_align=&#8221;justify&#8221; header_text_color=&#8221;#545454&#8243; header_font_size=&#8221;14px&#8221; text_orientation=&#8221;center&#8221; max_width_tablet=&#8221;600px&#8221; max_width_phone=&#8221;600px&#8221; max_width_last_edited=&#8221;on|phone&#8221; module_alignment=&#8221;center&#8221; header_font_size_tablet=&#8221;14px&#8221; header_font_size_phone=&#8221;14px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; module_alignment_tablet=&#8221;center&#8221; module_alignment_phone=&#8221;center&#8221; module_alignment_last_edited=&#8221;on|tablet&#8221; border_width_all=&#8221;0px&#8221; border_style_all_image=&#8221;none&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_blog][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; link_option_url=&#8221;https:\/\/mucciaccia.com\/it\/landscapes-maryam-eisler\/&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/mucciaccia.com\/wp-content\/uploads\/2023\/12\/song_for_freedom_mp.webp&#8221; alt=&#8221;Landscapes | Maryam Eisler&#8221; title_text=&#8221;song_for_freedom_mp&#8221; _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; height=&#8221;260px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Intimate Landscapes | Maryam Eisler<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.23.1&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;12px&#8221; text_line_height=&#8221;1rem&#8221; custom_padding=&#8221;||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Opening 9 febbraio 2024<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.23&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.23&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Header&#8221; _builder_version=&#8221;4.22.2&#8243; background_enable_image=&#8221;off&#8221; background_size=&#8221;initial&#8221; background_repeat=&#8221;repeat&#8221; custom_margin=&#8221;0px||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; use_custom_width=&#8221;on&#8221; width_unit=&#8221;off&#8221; custom_width_percent=&#8221;100%&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.22.2&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;|||on|||||&#8221; header_text_align=&#8221;center&#8221; header_font_size=&#8221;25px&#8221; header_line_height=&#8221;1.3em&#8221; header_2_font=&#8221;Prata|500|||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_font_size=&#8221;56px&#8221; header_2_line_height=&#8221;1.3em&#8221; header_3_font=&#8221;|700||on|||||&#8221; header_3_text_align=&#8221;center&#8221; header_3_text_color=&#8221;rgba(0,0,0,0.35)&#8221; header_3_font_size=&#8221;12px&#8221; header_3_letter_spacing=&#8221;5px&#8221; header_3_line_height=&#8221;2em&#8221; transform_translate_linked=&#8221;off&#8221; module_alignment=&#8221;center&#8221; header_font_size_tablet=&#8221;25px&#8221; header_font_size_phone=&#8221;15px&#8221; header_font_size_last_edited=&#8221;on|desktop&#8221; header_2_font_size_tablet=&#8221;40px&#8221; header_2_font_size_phone=&#8221;26px&#8221; header_2_font_size_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Mucciaccia Project | RomA<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Work&#8221; _builder_version=&#8221;4.22.2&#8243; background_color=&#8221;#ffffff&#8221; background_enable_image=&#8221;off&#8221; background_size=&#8221;initial&#8221; background_repeat=&#8221;repeat&#8221; custom_margin=&#8221;0px||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; disabled=&#8221;on&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row custom_padding_last_edited=&#8221;off|phone&#8221; _builder_version=&#8221;4.16&#8243; background_position=&#8221;bottom_center&#8221; custom_margin=&#8221;0px||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; custom_padding_tablet=&#8221;17vw||17vw||false&#8221; use_custom_width=&#8221;on&#8221; width_unit=&#8221;off&#8221; custom_width_percent=&#8221;100%&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.22.2&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;|500|||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_font_size=&#8221;24px&#8221; header_2_line_height=&#8221;1.3em&#8221; header_3_font=&#8221;|700||on|||||&#8221; header_3_text_align=&#8221;center&#8221; header_3_text_color=&#8221;rgba(0,0,0,0.35)&#8221; header_3_font_size=&#8221;12px&#8221; header_3_letter_spacing=&#8221;5px&#8221; header_3_line_height=&#8221;2em&#8221; transform_translate_linked=&#8221;off&#8221; max_width=&#8221;700px&#8221; module_alignment=&#8221;center&#8221; scroll_horizontal_motion_enable=&#8221;on&#8221; scroll_horizontal_motion=&#8221;0|50|50|100|4|0|0&#8243; header_2_font_size_tablet=&#8221;24px&#8221; header_2_font_size_phone=&#8221;16px&#8221; header_2_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Mostra in corso<\/h2>\n<p>[\/et_pb_text][et_pb_image src=&#8221;https:\/\/mucciaccia.com\/wp-content\/uploads\/2023\/09\/touching_the_sky_cover.webp&#8221; alt=&#8221;Touching The Sky&#8221; title_text=&#8221;Touching The Sky&#8221; url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wb3N0Iiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjIxMzAzIn19@&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.22.2&#8243; _dynamic_attributes=&#8221;url&#8221; _module_preset=&#8221;default&#8221; height=&#8221;500px&#8221; height_tablet=&#8221;450px&#8221; height_phone=&#8221;380px&#8221; height_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text ul_position=&#8221;inside&#8221; _builder_version=&#8221;4.22.2&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; text_font=&#8221;||||||||&#8221; ul_font=&#8221;||||||||&#8221; header_font=&#8221;|700|||||||&#8221; header_font_size=&#8221;20px&#8221; header_line_height=&#8221;1.3em&#8221; header_2_font_size=&#8221;40px&#8221; header_3_font=&#8221;|700|||||||&#8221; header_3_font_size=&#8221;24px&#8221; header_3_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;||0px||false|false&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wb3N0Iiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjIxMzAzIn19@&#8221; header_2_font_size_tablet=&#8221;26px&#8221; header_2_font_size_phone=&#8221;&#8221; header_2_font_size_last_edited=&#8221;on|desktop&#8221; header_3_font_size_tablet=&#8221;&#8221; header_3_font_size_phone=&#8221;&#8221; header_3_font_size_last_edited=&#8221;on|desktop&#8221; text_text_align=&#8221;center&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Touching the Sky | Tiffanie Delune &amp; Sola Olulode<\/h3>\n<p>04 ottobre \u2013 12 novembre 2023<\/p>\n<p>[\/et_pb_text][et_pb_post_slider include_categories=&#8221;195&#8243; use_manual_excerpt=&#8221;off&#8221; excerpt_length=&#8221;0&#8243; show_meta=&#8221;off&#8221; image_placement=&#8221;top&#8221; use_text_overlay=&#8221;off&#8221; show_image_video_mobile=&#8221;on&#8221; show_image_tablet=&#8221;&#8221; show_image_phone=&#8221;&#8221; show_image_last_edited=&#8221;on|desktop&#8221; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; header_level=&#8221;h3&#8243; header_font=&#8221;|600|||||||&#8221; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;30px&#8221; body_text_color=&#8221;#ffffff&#8221; background_color=&#8221;#ffffff&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;16px&#8221; background_layout=&#8221;light&#8221; box_shadow_style_image=&#8221;preset2&#8243; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_post_slider][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.16&#8243; scroll_blur_enable=&#8221;on&#8221; motion_trigger_start=&#8221;top&#8221; scroll_blur_tablet=&#8221;&#8221; scroll_blur_phone=&#8221;0|50|50|100|10px|0px|0px&#8221; scroll_blur_last_edited=&#8221;on|phone&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/mucciaccia.com\/wp-content\/uploads\/2020\/09\/see-saw-fh-ny-300&#215;300.jpg&#8221; alt=&#8221;SEE\/SAW \u2013 Frank Holliday New York&#8221; title_text=&#8221;see-saw-fh-ny&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.16&#8243; border_width_all=&#8221;20px&#8221; border_color_all=&#8221;#ffffff&#8221; border_width_all_last_edited=&#8221;off|desktop&#8221; box_shadow_style=&#8221;preset4&#8243; box_shadow_horizontal=&#8221;0px&#8221; box_shadow_vertical=&#8221;0px&#8221; box_shadow_spread=&#8221;1px&#8221; box_shadow_color=&#8221;rgba(0,0,0,0.34)&#8221; global_colors_info=&#8221;{}&#8221; box_shadow_color__hover=&#8221;#000000&#8243; box_shadow_color__hover_enabled=&#8221;on&#8221; border_width_all__hover_enabled=&#8221;on&#8221; border_width_all__hover=&#8221;30px&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text ul_position=&#8221;inside&#8221; _builder_version=&#8221;4.16&#8243; text_font=&#8221;||||||||&#8221; ul_font=&#8221;||||||||&#8221; header_font=&#8221;|700|||||||&#8221; header_font_size=&#8221;20px&#8221; header_line_height=&#8221;1.3em&#8221; header_2_font_size=&#8221;40px&#8221; header_3_font=&#8221;|700|||||||&#8221; header_3_font_size=&#8221;24px&#8221; header_3_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;||0px||false|false&#8221; text_text_align=&#8221;center&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>SEE\/SAW<\/h2>\n<h3>Frank Holliday<\/h3>\n<p>Until Semptember 30, 2020<\/p>\n<p>[\/et_pb_text][et_pb_text ul_position=&#8221;inside&#8221; _builder_version=&#8221;4.16&#8243; text_font=&#8221;||||||||&#8221; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;1.6em&#8221; ul_font=&#8221;||||||||&#8221; header_font=&#8221;|700|||||||&#8221; header_font_size=&#8221;20px&#8221; header_line_height=&#8221;1.3em&#8221; header_3_font=&#8221;|700|||||||&#8221; header_3_font_size=&#8221;14px&#8221; header_3_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;10px||||false|false&#8221; custom_padding=&#8221;10px||||false|false&#8221; border_width_top=&#8221;2px&#8221; border_color_top=&#8221;#e2e2d3&#8243; text_text_align=&#8221;center&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: justify;\"><span>Mucciaccia Gallery is proud to present an extensive exhibition on the American artist, Frank Holliday.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Work&#8221; _builder_version=&#8221;4.16&#8243; background_enable_image=&#8221;off&#8221; background_size=&#8221;initial&#8221; background_repeat=&#8221;repeat&#8221; custom_margin=&#8221;0px||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; disabled=&#8221;on&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row custom_padding_last_edited=&#8221;off|phone&#8221; _builder_version=&#8221;4.16&#8243; background_position=&#8221;bottom_center&#8221; custom_padding_tablet=&#8221;17vw||17vw||false&#8221; use_custom_width=&#8221;on&#8221; width_unit=&#8221;off&#8221; custom_width_percent=&#8221;100%&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;|500|||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_font_size=&#8221;35px&#8221; header_2_line_height=&#8221;1.3em&#8221; header_3_font=&#8221;|700||on|||||&#8221; header_3_text_align=&#8221;center&#8221; header_3_text_color=&#8221;rgba(0,0,0,0.35)&#8221; header_3_font_size=&#8221;12px&#8221; header_3_letter_spacing=&#8221;5px&#8221; header_3_line_height=&#8221;2em&#8221; transform_translate_linked=&#8221;off&#8221; max_width=&#8221;700px&#8221; max_width_tablet=&#8221;70%&#8221; max_width_last_edited=&#8221;off|phone&#8221; module_alignment=&#8221;center&#8221; scroll_horizontal_motion_enable=&#8221;on&#8221; scroll_horizontal_motion=&#8221;0|50|50|100|4|0|0&#8243; header_2_font_size_tablet=&#8221;40px&#8221; header_2_font_size_phone=&#8221;26px&#8221; header_2_font_size_last_edited=&#8221;on|tablet&#8221; header_3_font_size_phone=&#8221;10px&#8221; header_3_font_size_last_edited=&#8221;off|desktop&#8221; module_alignment_last_edited=&#8221;off|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>On Display Now\u00a0<\/h3>\n<h2>Current Exhibitions<\/h2>\n<p>[\/et_pb_text][et_pb_post_slider include_categories=&#8221;167&#8243; excerpt_length=&#8221;0&#8243; show_meta=&#8221;off&#8221; image_placement=&#8221;top&#8221; use_text_overlay=&#8221;off&#8221; show_image_video_mobile=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; header_level=&#8221;h3&#8243; header_font=&#8221;|600|||||||&#8221; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;30px&#8221; body_text_color=&#8221;#ffffff&#8221; background_color=&#8221;#ffffff&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;16px&#8221; background_layout=&#8221;light&#8221; box_shadow_style_image=&#8221;preset2&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_post_slider][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.16&#8243; scroll_blur_enable=&#8221;on&#8221; motion_trigger_start=&#8221;top&#8221; scroll_blur_tablet=&#8221;&#8221; scroll_blur_phone=&#8221;0|50|50|100|10px|0px|0px&#8221; scroll_blur_last_edited=&#8221;on|phone&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/mucciaccia.com\/wp-content\/uploads\/2020\/09\/see-saw-fh-ny-300&#215;300.jpg&#8221; alt=&#8221;SEE\/SAW \u2013 Frank Holliday New York&#8221; title_text=&#8221;see-saw-fh-ny&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.16&#8243; border_width_all=&#8221;20px&#8221; border_color_all=&#8221;#ffffff&#8221; border_width_all_last_edited=&#8221;off|desktop&#8221; box_shadow_style=&#8221;preset4&#8243; box_shadow_horizontal=&#8221;0px&#8221; box_shadow_vertical=&#8221;0px&#8221; box_shadow_spread=&#8221;1px&#8221; box_shadow_color=&#8221;rgba(0,0,0,0.34)&#8221; global_colors_info=&#8221;{}&#8221; box_shadow_color__hover=&#8221;#000000&#8243; box_shadow_color__hover_enabled=&#8221;on&#8221; border_width_all__hover_enabled=&#8221;on&#8221; border_width_all__hover=&#8221;30px&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text ul_position=&#8221;inside&#8221; _builder_version=&#8221;4.16&#8243; text_font=&#8221;||||||||&#8221; ul_font=&#8221;||||||||&#8221; header_font=&#8221;|700|||||||&#8221; header_font_size=&#8221;20px&#8221; header_line_height=&#8221;1.3em&#8221; header_2_font_size=&#8221;40px&#8221; header_3_font=&#8221;|700|||||||&#8221; header_3_font_size=&#8221;24px&#8221; header_3_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;||0px||false|false&#8221; text_text_align=&#8221;center&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>SEE\/SAW<\/h2>\n<h3>Frank Holliday<\/h3>\n<p>Until Semptember 30, 2020<\/p>\n<p>[\/et_pb_text][et_pb_text ul_position=&#8221;inside&#8221; _builder_version=&#8221;4.16&#8243; text_font=&#8221;||||||||&#8221; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;1.6em&#8221; ul_font=&#8221;||||||||&#8221; header_font=&#8221;|700|||||||&#8221; header_font_size=&#8221;20px&#8221; header_line_height=&#8221;1.3em&#8221; header_3_font=&#8221;|700|||||||&#8221; header_3_font_size=&#8221;14px&#8221; header_3_line_height=&#8221;1.3em&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;10px||||false|false&#8221; custom_padding=&#8221;10px||||false|false&#8221; border_width_top=&#8221;2px&#8221; border_color_top=&#8221;#e2e2d3&#8243; text_text_align=&#8221;center&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: justify;\"><span>Mucciaccia Gallery is proud to present an extensive exhibition on the American artist, Frank Holliday.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;off|off|off&#8221; admin_label=&#8221;Header&#8221; _builder_version=&#8221;4.16&#8243; background_enable_image=&#8221;off&#8221; background_size=&#8221;initial&#8221; background_repeat=&#8221;repeat&#8221; custom_margin=&#8221;0px||||false|false&#8221; custom_padding=&#8221;60px||||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.22.2&#8243; use_custom_width=&#8221;on&#8221; width_unit=&#8221;off&#8221; custom_width_percent=&#8221;100%&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;||||||||&#8221; header_2_font=&#8221;|500|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_font_size=&#8221;23px&#8221; header_3_font=&#8221;|700||on|||||&#8221; header_3_text_color=&#8221;rgba(0,0,0,0.35)&#8221; header_3_font_size=&#8221;12px&#8221; header_3_letter_spacing=&#8221;5px&#8221; header_3_line_height=&#8221;2em&#8221; transform_translate_linked=&#8221;off&#8221; text_orientation=&#8221;center&#8221; module_alignment=&#8221;center&#8221; hover_transition_duration=&#8221;0ms&#8221; header_2_font_size_tablet=&#8221;23px&#8221; header_2_font_size_phone=&#8221;16px&#8221; header_2_font_size_last_edited=&#8221;on|tablet&#8221; text_text_align=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Mostre passate<\/h2>\n<p>[\/et_pb_text][et_pb_divider _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_blog fullwidth=&#8221;off&#8221; posts_number=&#8221;40&#8243; include_categories=&#8221;277&#8243; show_author=&#8221;off&#8221; show_date=&#8221;off&#8221; show_categories=&#8221;off&#8221; show_excerpt=&#8221;off&#8221; show_pagination=&#8221;off&#8221; module_class=&#8221;et_blog_grid_equal_height&#8221; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; header_level=&#8221;h3&#8243; header_font=&#8221;|600|||||||&#8221; header_text_align=&#8221;justify&#8221; header_text_color=&#8221;#545454&#8243; header_font_size=&#8221;14px&#8221; text_orientation=&#8221;center&#8221; max_width_tablet=&#8221;600px&#8221; max_width_phone=&#8221;600px&#8221; max_width_last_edited=&#8221;on|phone&#8221; module_alignment=&#8221;center&#8221; header_font_size_tablet=&#8221;14px&#8221; header_font_size_phone=&#8221;14px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; module_alignment_tablet=&#8221;center&#8221; module_alignment_phone=&#8221;center&#8221; module_alignment_last_edited=&#8221;on|tablet&#8221; border_width_all=&#8221;0px&#8221; border_style_all_image=&#8221;none&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_blog][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Header&#8221; _builder_version=&#8221;4.27.4&#8243; background_enable_image=&#8221;off&#8221; background_size=&#8221;initial&#8221; background_repeat=&#8221;repeat&#8221; custom_margin=&#8221;0px||0px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; background_color=&#8221;rgba(0,0,0,0)&#8221; use_custom_width=&#8221;on&#8221; width_unit=&#8221;off&#8221; custom_width_percent=&#8221;100%&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_divider _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;on|on|on&#8221; admin_label=&#8221;Email&#8221; _builder_version=&#8221;4.27.4&#8243; background_enable_image=&#8221;off&#8221; background_size=&#8221;initial&#8221; background_repeat=&#8221;repeat&#8221; custom_margin=&#8221;0px||0px||false|false&#8221; custom_padding=&#8221;0px||||false|false&#8221; disabled=&#8221;on&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.19.2&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_image src=&#8221;https:\/\/mucciaccia.com\/wp-content\/uploads\/2023\/09\/mucciaccia_contemporary_roma_map.webp&#8221; alt=&#8221;Map Galleria Mucciaccia Rome (Google Map)&#8221; title_text=&#8221;mucciaccia_contemporary_roma_map&#8221; url=&#8221;https:\/\/www.google.com\/maps?ll=41.903556,12.476466&#038;z=16&#038;t=m&#038;hl=it&#038;gl=IT&#038;mapclient=embed&#038;q=Largo+della+Fontanella+di+Borghese,+89+00186+Roma+RM&#8221; url_new_window=&#8221;on&#8221; _builder_version=&#8221;4.22.2&#8243; _module_preset=&#8221;default&#8221; filter_saturate=&#8221;0%&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_code disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;]<p class=\"wpcf7-contact-form-not-found\"><strong>Errore:<\/strong> Modulo di contatto non trovato.<\/p>[\/et_pb_code][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;20px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Indirizzo<\/p>\n<h2><strong>MUCCIACCIA GALLERY ROMA<\/strong><\/h2>\n<p><span>Via Laurina, 31<\/span><br \/><span>00187 \u2013 Roma<\/span><br \/><span>Tel. +39 06.79783647<br \/>roma@mucciaccia.com<br \/>project@mucciaccia.com<\/span><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;mailto:project@mucciaccia.com?subject=Website%20request&#038;body=Your%20message&#8221; button_text=&#8221;Contattaci&#8221; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; disabled=&#8221;on&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Footer&#8221; _builder_version=&#8221;4.16&#8243; background_size=&#8221;initial&#8221; background_repeat=&#8221;repeat-y&#8221; custom_padding=&#8221;0px|||||&#8221; saved_tabs=&#8221;all&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; use_custom_gutter=&#8221;on&#8221; _builder_version=&#8221;4.23.1&#8243; border_width_top=&#8221;1px&#8221; border_color_top=&#8221;#c9c9c9&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text content_last_edited=&#8221;off|desktop&#8221; module_class=&#8221;hyperlink-color&#8221; _builder_version=&#8221;4.27.5&#8243; text_font=&#8221;||||||||&#8221; text_font_size=&#8221;1rem&#8221; text_line_height=&#8221;1.2rem&#8221; link_font=&#8221;||||on|||rgba(0,0,0,0)|&#8221; link_text_color=&#8221;#666666&#8243; header_font=&#8221;||||||||&#8221; header_text_align=&#8221;left&#8221; header_3_font=&#8221;|700||on|||||&#8221; header_3_font_size=&#8221;12px&#8221; header_3_line_height=&#8221;1.8em&#8221; header_6_font=&#8221;|700||on|||||&#8221; header_6_text_color=&#8221;#474747&#8243; header_6_font_size=&#8221;12px&#8221; header_6_line_height=&#8221;1.8em&#8221; link_font_tablet=&#8221;&#8221; link_font_phone=&#8221;&#8221; link_font_last_edited=&#8221;on|desktop&#8221; header_3_font_size_tablet=&#8221;&#8221; header_3_font_size_phone=&#8221;&#8221; header_3_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; content__hover_enabled=&#8221;off|desktop&#8221; content__hover=&#8221;<\/p>\n<h6>Address<\/h6>\n<h6><strong><a title=%22ROME | Galleria Mucciaccia%22 href=%22\/en?page_id=21312%22><span>Mucciaccia Project | ROME<\/span><\/a><\/strong><\/h6>\n<p>Via Laurina, 31<br \/>00187 \u2013 Roma<br \/>Tel. +39 06.79783647<\/p>\n<p>&#8220;]<\/p>\n<h3>Indirizzo<\/h3>\n<p>MUCCIACCIA GALLERY | ROMA<br \/>Via Laurina 31<br \/>00187 \u2013 Roma<br \/><a href=\"tel:+39%2006.69923801\"><\/a><span>Tel.\u00a0<\/span><a href=\"tel:+390679783647\">+39 06.79783647<\/a><br \/>roma@mucciaccia.com<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text module_class=&#8221;hyperlink-color&#8221; _builder_version=&#8221;4.27.4&#8243; text_font=&#8221;||||||||&#8221; text_font_size=&#8221;1rem&#8221; text_line_height=&#8221;1.2rem&#8221; link_font=&#8221;||||on|||rgba(0,0,0,0)|&#8221; link_text_color=&#8221;#666666&#8243; header_font=&#8221;||||||||&#8221; header_text_align=&#8221;left&#8221; header_3_font=&#8221;|700||on|||||&#8221; header_3_font_size=&#8221;12px&#8221; header_3_letter_spacing=&#8221;5px&#8221; header_3_line_height=&#8221;1.8em&#8221; header_6_font=&#8221;|700||on|||||&#8221; header_6_text_color=&#8221;#474747&#8243; header_6_font_size=&#8221;12px&#8221; header_6_line_height=&#8221;1.8em&#8221; link_font_tablet=&#8221;||||on|||rgba(0,0,0,0)|&#8221; link_font_phone=&#8221;||||on|||rgba(0,0,0,0)|&#8221; link_font_last_edited=&#8221;on|desktop&#8221; header_3_font_size_tablet=&#8221;&#8221; header_3_font_size_phone=&#8221;&#8221; header_3_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h6>Orari<\/h6>\n<p>Luned\u00ec \u2013 venerd\u00ec 10.30 \u2013 19.00<br \/>Sabato 11.00 \u2013 19.00<em> <\/em><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.23.1&#8243; custom_padding=&#8221;|||&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text module_class=&#8221;hyperlink-color&#8221; _builder_version=&#8221;4.19.4&#8243; text_font=&#8221;||||||||&#8221; text_font_size=&#8221;12px&#8221; text_line_height=&#8221;2em&#8221; link_font=&#8221;||||on|||rgba(0,0,0,0)|&#8221; link_text_color=&#8221;#666666&#8243; header_font=&#8221;||||||||&#8221; header_text_align=&#8221;left&#8221; header_3_font=&#8221;|700||on|||||&#8221; header_3_font_size=&#8221;12px&#8221; header_3_letter_spacing=&#8221;5px&#8221; header_3_line_height=&#8221;1.8em&#8221; header_6_font=&#8221;|700||on|||||&#8221; header_6_text_color=&#8221;#474747&#8243; header_6_font_size=&#8221;12px&#8221; header_6_line_height=&#8221;1.8em&#8221; link_font_tablet=&#8221;||||on|||rgba(0,0,0,0)|&#8221; link_font_phone=&#8221;||||on|||rgba(0,0,0,0)|&#8221; link_font_last_edited=&#8221;on|desktop&#8221; header_3_font_size_tablet=&#8221;&#8221; header_3_font_size_phone=&#8221;&#8221; header_3_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h6>Follow<\/h6>\n<p>[\/et_pb_text][et_pb_social_media_follow _builder_version=&#8221;4.16&#8243; custom_margin=&#8221;-20px|||-10px&#8221; custom_margin_tablet=&#8221;&#8221; custom_margin_phone=&#8221;-20px||&#8221; custom_margin_last_edited=&#8221;on|desktop&#8221; filter_invert=&#8221;100%&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; icon_color__hover=&#8221;#e02b20&#8243;][et_pb_social_media_follow_network social_network=&#8221;facebook&#8221; url=&#8221;https:\/\/www.facebook.com\/mucciacciaart\/&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]facebook[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;instagram&#8221; url=&#8221;https:\/\/www.instagram.com\/mucciacciagallery\/&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]instagram[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MUCCIACCIA GALLERY | ROMA Summer Collection 2026 10 giugno &#8211; 31 agosto 2026Open CallSummer Exhibition | Chiamata alle Arti | 2024 Open Call &#8211; Invito di partecipazione a tutte le Accademie di Belle Arti in Italia Mucciaccia Gallery Project\u00a0 \u00e8 lieta di annunciare la quarta edizione di Chiamata alle Arti che si terr\u00e0 durante i [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":21317,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-21313","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/mucciaccia.com\/it\/wp-json\/wp\/v2\/pages\/21313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mucciaccia.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mucciaccia.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mucciaccia.com\/it\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/mucciaccia.com\/it\/wp-json\/wp\/v2\/comments?post=21313"}],"version-history":[{"count":5,"href":"https:\/\/mucciaccia.com\/it\/wp-json\/wp\/v2\/pages\/21313\/revisions"}],"predecessor-version":[{"id":30833,"href":"https:\/\/mucciaccia.com\/it\/wp-json\/wp\/v2\/pages\/21313\/revisions\/30833"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mucciaccia.com\/it\/wp-json\/wp\/v2\/media\/21317"}],"wp:attachment":[{"href":"https:\/\/mucciaccia.com\/it\/wp-json\/wp\/v2\/media?parent=21313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}